{"id":65,"date":"2000-06-09T14:54:05","date_gmt":"2000-06-09T13:54:05","guid":{"rendered":"http:\/\/kurios.at\/storys\/65"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"Frau-in-SEX-Anzeige-war-eigene-Schwester","status":"publish","type":"post","link":"https:\/\/kurios.at\/storys\/65\/Frau-in-SEX-Anzeige-war-eigene-Schwester\/","title":{"rendered":"Frau in SEX-Anzeige war eigene Schwester"},"content":{"rendered":"<h1 class=\"storys\"><CENTER>Frau in SEX-Anzeige war eigene Schwester<\/h1>\n<p><\/center><font class=\"storys\"><br \/>\n<br \/>\n<b>Mailand<\/b> &#8211; Der geplante SEX-Ausflug eines 27j&auml;hrigen aus einem italienischen Dorf nach Mailand endete mit einer unliebsamen<br \/>\n\u00dcberraschung: Als ihm das Liebesm&auml;dchen, das dich in einem Zeitungsinserat angeboten hatte, die T&uuml;r &ouml;ffnete, stand<br \/>\nder &#8220;Freier&#8221; vor seiner eigene Schwester. Der Mann verlor vor lauter Schreck das Bewusstsein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frau in SEX-Anzeige war eigene Schwester Mailand &#8211; Der geplante SEX-Ausflug eines 27j&auml;hrigen aus einem italienischen Dorf nach Mailand endete mit einer unliebsamen \u00dcberraschung: Als ihm das Liebesm&auml;dchen, das dich in einem Zeitungsinserat angeboten hatte, die T&uuml;r &ouml;ffnete, stand der &#8220;Freier&#8221; vor seiner eigene Schwester. Der Mann verlor vor lauter Schreck das Bewusstsein.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":0,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"wp:attachment":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}