{"id":705,"date":"2010-02-14T22:16:51","date_gmt":"2010-02-14T20:16:51","guid":{"rendered":"http:\/\/kurios.at\/storys\/?p=705"},"modified":"2010-02-14T22:17:47","modified_gmt":"2010-02-14T20:17:47","slug":"taxigast-springt-aus-fahrendem-taxi","status":"publish","type":"post","link":"https:\/\/kurios.at\/storys\/705\/taxigast-springt-aus-fahrendem-taxi\/","title":{"rendered":"Taxigast springt aus fahrendem Taxi"},"content":{"rendered":"<h1 class=\"storys\"><center>K\u00e4rntner springt bei Tempo 50 aus fahrendem Taxi<\/center><\/h1>\n<p><font class=\"storys\"><br \/>\n<\/p>\n<table>\n<tr>\n<td align=\"justify\">\nKuriose Szenen am Sonntagmorgen im Lavanttal: Ein 24-j\u00e4hriger K\u00e4rntner ist bei Tempo 50 aus einem fahrenden Taxi gesprungen. Der vermeintliche Fahrpreis war ihm zu hoch erschienen. Er kam mit Hautabsch\u00fcrfungen davon.<\/p>\n<p>Der Mann, ein 24-J\u00e4hriger aus Bad St. Leonhard, wollte sich gegen halb sechs Uhr in der Fr\u00fch nach Hause bringen lassen. W\u00e4hrend der Fahrt gab ihm die Taxilenkerin bekannt, dass der Preis f\u00fcr die Fuhre etwa sieben Euro betragen werde.\n<\/td>\n<td align=\"right\" width=\"285\" valign=\"top\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/kurios.at\/storys\/wp-content\/uploads\/2010\/02\/taxi1.jpg\" alt=\"\" title=\"taxi\" width=\"275\" height=\"138\" class=\"alignnone size-full wp-image-707\" \/>\n<\/td>\n<\/tr>\n<\/table>\n<p>Der Mann verstand jedoch &#8220;17 Euro&#8221; und erkl\u00e4rte, dies sei ihm zu viel. Er \u00f6ffnete die seitliche Schiebet\u00fcr des Autos und sprang hinaus. Er erlitt zahlreiche Absch\u00fcrfungen am linken Unterarm und im Gesicht und wurde ins Landeskrankenhaus nach Wolfsberg gebracht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00e4rntner springt bei Tempo 50 aus fahrendem Taxi Kuriose Szenen am Sonntagmorgen im Lavanttal: Ein 24-j\u00e4hriger K\u00e4rntner ist bei Tempo 50 aus einem fahrenden Taxi gesprungen. Der vermeintliche Fahrpreis war ihm zu hoch erschienen. Er kam mit Hautabsch\u00fcrfungen davon. Der Mann, ein 24-J\u00e4hriger aus Bad St. Leonhard, wollte sich gegen halb sechs Uhr in der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[848,846,847,407],"class_list":["post-705","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-darwin-award","tag-karntner","tag-springen","tag-taxi"],"_links":{"self":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts\/705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/comments?post=705"}],"version-history":[{"count":0,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/posts\/705\/revisions"}],"wp:attachment":[{"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/media?parent=705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/categories?post=705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kurios.at\/storys\/wp-json\/wp\/v2\/tags?post=705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}